{"id":18221,"date":"2024-04-16T10:48:18","date_gmt":"2024-04-16T07:48:18","guid":{"rendered":"https:\/\/ceramic.md\/?post_type=product&#038;p=18221"},"modified":"2024-04-17T11:58:31","modified_gmt":"2024-04-17T08:58:31","slug":"egger-pro-epl191","status":"publish","type":"product","link":"https:\/\/ceramic.md\/ro\/product\/egger-pro-epl191\/","title":{"rendered":"Egger PRO EPL191 8mm"},"content":{"rendered":"<h2><span style=\"font-size: 75%;\">Laminat pentru podea Egger PRO EPL191<\/span><\/h2>\n<div class=\"row\"  id=\"row-550273688\">\n\n\t<div id=\"col-1004770495\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"8 \u043c\u043c grosimea pl\u0103cii\" style=\"margin:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/8mm-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/8mm-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/8mm-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1428479565\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"AC4 clasa de abraziune\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/ac4-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/ac4-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/ac4-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1825130562\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"32 clasa de rezisten\u021b\u0103\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/class-32-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/class-32-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/class-32-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1818626790\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"20 ani garan\u021bie \u00een spa\u021bii de locuit\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/20years-garranty-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/20years-garranty-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/20years-garranty-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-488052067\">\n\n\t<div id=\"col-1737867495\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"pentru podele calde\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/warm-floor-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/warm-floor-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/warm-floor-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1280595794\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"Structura Deepskin\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2024\/04\/deepskin-structure-icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2024\/04\/deepskin-structure-icon.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2024\/04\/deepskin-structure-icon-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1821965504\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"antibacterial\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"157\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/bez-imeni.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/bez-imeni.png 157w, https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/bez-imeni-100x100.png 100w\" sizes=\"(max-width: 157px) 100vw, 157px\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1206466062\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left tooltip text-left is-small\" title=\"fasca din 4 p\u0103r\u021bi\" >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"163\" height=\"157\" src=\"https:\/\/ceramic.md\/wp-content\/uploads\/2021\/12\/v4-icon.png\" class=\"attachment-medium size-medium\" alt=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Cantitatea pachetului<\/strong><strong>:<\/strong> 1,995 m\u00b2 (8 buc)<\/p>\n<p><strong>Greutatea pachetului<\/strong><strong>:<\/strong> 14,0 kg<\/p>\n<p><strong>Dime<span style=\"font-size: 100%;\">nsiune foaiei<\/span><\/strong><span style=\"font-size: 100%;\"><strong>:\u00a0<\/strong>1292x193x<a href=\"https:\/\/ceramic.md\/grosime\/8mm\/\">8 mm<\/a><\/span><\/p>\n<p><strong>Clasa de rezisten\u021b\u0103:<\/strong> AC4\/32<\/p>\n<p><strong>Produc\u0103tor<\/strong><strong>:<\/strong> <a href=\"https:\/\/www.egger.com\/\" target=\"_blank\" rel=\"noopener\">Egger<\/a>, Germania<\/p>\n<p><strong>Colec\u021bie<\/strong><strong>:<\/strong> Classic PRO","protected":false},"excerpt":{"rendered":"<p><strong>Laminat<\/strong> 8 mm, clasa 32 &#8211; PRO EPL191<\/p>\n","protected":false},"featured_media":18226,"template":"","meta":[],"product_cat":[616,39],"product_tag":[],"_links":{"self":[{"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/product\/18221"}],"collection":[{"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/media\/18226"}],"wp:attachment":[{"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/media?parent=18221"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/product_cat?post=18221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ceramic.md\/ro\/wp-json\/wp\/v2\/product_tag?post=18221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}